{"id":13056,"date":"2024-12-05T17:04:33","date_gmt":"2024-12-05T17:04:33","guid":{"rendered":"https:\/\/trivec.eu\/producten\/querschneider-double\/"},"modified":"2024-12-05T17:04:33","modified_gmt":"2024-12-05T17:04:33","slug":"querschneider-double","status":"publish","type":"producten","link":"https:\/\/trivec.eu\/de\/producten\/querschneider-double\/","title":{"rendered":"Querschneider Double"},"content":{"rendered":"<p>Der Cross Cutter Double wurde entwickelt, um Bands\u00e4geeffekte auf Holzoberfl\u00e4chen zu erzielen. Durch die Anpassung der Durchlaufgeschwindigkeit, der Schleifbandgeschwindigkeit, der Winkeleinstellungen der Schleifbandeinheit, des Drucks auf die Werkst\u00fcckoberfl\u00e4che und der Art des Schleifbands bietet die Maschine gro\u00dfe Flexibilit\u00e4t, um den gew\u00fcnschten Effekt zu erzielen. <\/p>\n<p>Diese Version verf\u00fcgt \u00fcber zwei Cross-Cut-Aggregate, die eine tiefere Bands\u00e4gestruktur erm\u00f6glichen. Sie erm\u00f6glicht auch den Einsatz verschiedener Schleifbandtypen in einem einzigen Durchgang und die M\u00f6glichkeit, mit \u00fcberlappenden Schleifrichtungen zu experimentieren. Diese Funktionen erh\u00f6hen die Vielseitigkeit der Maschine und die Bandbreite der erzielbaren Effekte noch weiter.  <\/p>\n","protected":false},"featured_media":13059,"parent":0,"template":"","branches":[112,113,111],"types":[121],"technieken":[120],"class_list":["post-13056","producten","type-producten","status-publish","has-post-thumbnail","hentry","branches-auseres-holz","branches-holz-innen","branches-parkett","types-querschneider","technieken-oberflachenlosungen"],"_links":{"self":[{"href":"https:\/\/trivec.eu\/de\/wp-json\/wp\/v2\/producten\/13056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trivec.eu\/de\/wp-json\/wp\/v2\/producten"}],"about":[{"href":"https:\/\/trivec.eu\/de\/wp-json\/wp\/v2\/types\/producten"}],"version-history":[{"count":0,"href":"https:\/\/trivec.eu\/de\/wp-json\/wp\/v2\/producten\/13056\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trivec.eu\/de\/wp-json\/wp\/v2\/media\/13059"}],"wp:attachment":[{"href":"https:\/\/trivec.eu\/de\/wp-json\/wp\/v2\/media?parent=13056"}],"wp:term":[{"taxonomy":"branches","embeddable":true,"href":"https:\/\/trivec.eu\/de\/wp-json\/wp\/v2\/branches?post=13056"},{"taxonomy":"types","embeddable":true,"href":"https:\/\/trivec.eu\/de\/wp-json\/wp\/v2\/types?post=13056"},{"taxonomy":"technieken","embeddable":true,"href":"https:\/\/trivec.eu\/de\/wp-json\/wp\/v2\/technieken?post=13056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}