{"id":17209,"date":"2024-12-05T17:04:44","date_gmt":"2024-12-05T17:04:44","guid":{"rendered":"https:\/\/trivec.eu\/producten\/encoladora-de-rodillos\/"},"modified":"2024-12-05T17:04:44","modified_gmt":"2024-12-05T17:04:44","slug":"encoladora-de-rodillos","status":"publish","type":"producten","link":"https:\/\/trivec.eu\/es\/producten\/encoladora-de-rodillos\/","title":{"rendered":"Encoladora de rodillos"},"content":{"rendered":"<p>El Rodillo Recubridor para Cola Trivec est\u00e1 dise\u00f1ado para aplicar adhesivos como la cola a diversas superficies de piezas de trabajo, como chapa de madera, chapa de aluminio y otros materiales utilizados en la industria del mueble, el parqu\u00e9 y la carpinter\u00eda. Tambi\u00e9n es adecuada para materiales como pl\u00e1stico, cart\u00f3n, textil, madera, etc. <\/p>\n<p>La encoladora de rodillos para cola utiliza un sistema de aplicaci\u00f3n de cola de precisi\u00f3n controlada con rodillos dosificadores y aplicadores ajustables para garantizar una distribuci\u00f3n uniforme y precisa de la cola. Las velocidades de los rodillos y el sentido de giro pueden ajustarse con precisi\u00f3n para adaptarse a los requisitos espec\u00edficos de tu proceso de producci\u00f3n. <\/p>\n","protected":false},"featured_media":17211,"parent":0,"template":"","branches":[157,158,159,160],"types":[190],"technieken":[170],"class_list":["post-17209","producten","type-producten","status-publish","has-post-thumbnail","hentry","branches-parquet","branches-madera-exterior","branches-madera-interior","branches-otros","types-aplicadores-de-cola","technieken-soluciones-de-pegamento"],"_links":{"self":[{"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/producten\/17209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/producten"}],"about":[{"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/types\/producten"}],"version-history":[{"count":0,"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/producten\/17209\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/media\/17211"}],"wp:attachment":[{"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/media?parent=17209"}],"wp:term":[{"taxonomy":"branches","embeddable":true,"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/branches?post=17209"},{"taxonomy":"types","embeddable":true,"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/types?post=17209"},{"taxonomy":"technieken","embeddable":true,"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/technieken?post=17209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}