{"id":17316,"date":"2024-12-05T17:04:44","date_gmt":"2024-12-05T17:04:44","guid":{"rendered":"https:\/\/trivec.eu\/producten\/cepilladora-con-cepillo-lateral\/"},"modified":"2024-12-05T17:04:44","modified_gmt":"2024-12-05T17:04:44","slug":"cepilladora-con-cepillo-lateral","status":"publish","type":"producten","link":"https:\/\/trivec.eu\/es\/producten\/cepilladora-con-cepillo-lateral\/","title":{"rendered":"Cepilladora con cepillo lateral"},"content":{"rendered":"<div class=\"flex-shrink-0 flex flex-col relative items-end\">\n<div>\n<div class=\"pt-0\">\n<div class=\"gizmo-bot-avatar flex h-8 w-8 items-center justify-center overflow-hidden rounded-full\">\n<div class=\"relative p-1 rounded-sm flex items-center justify-center bg-token-main-surface-primary text-token-text-primary h-8 w-8\">Dispone de dos cepillos horizontales y uno vertical, todos ellos ajustables en \u00e1ngulo para conseguir un lijado preciso y efectos de grano, con ajustes de altura central y fina que garantizan un procesamiento preciso para diversas piezas de trabajo. El cepillo vertical funciona junto a un lineal de gu\u00eda para mantener una alineaci\u00f3n perfecta. Los motores de alta resistencia ofrecen un control independiente de la velocidad y la rotaci\u00f3n, lo que permite una flexibilidad creativa, mientras que la presi\u00f3n ajustable, el tipo de cepillo, el \u00e1ngulo y la velocidad de la cinta mejoran a\u00fan m\u00e1s la versatilidad. Compatible con cepillos Tynex, messing bundle, Scotch Brite y lijadores, esta m\u00e1quina es ideal para estructurar, limpiar y envejecer superficies de madera.   <\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":17318,"parent":0,"template":"","branches":[158,159],"types":[185,186],"technieken":[183],"class_list":["post-17316","producten","type-producten","status-publish","has-post-thumbnail","hentry","branches-madera-exterior","branches-madera-interior","types-cepillado","types-lijado","technieken-soluciones-de-superficie"],"_links":{"self":[{"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/producten\/17316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/producten"}],"about":[{"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/types\/producten"}],"version-history":[{"count":0,"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/producten\/17316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/media\/17318"}],"wp:attachment":[{"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/media?parent=17316"}],"wp:term":[{"taxonomy":"branches","embeddable":true,"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/branches?post=17316"},{"taxonomy":"types","embeddable":true,"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/types?post=17316"},{"taxonomy":"technieken","embeddable":true,"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/technieken?post=17316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}