{"id":17417,"date":"2024-12-05T17:04:29","date_gmt":"2024-12-05T17:04:29","guid":{"rendered":"https:\/\/trivec.eu\/producten\/cepilladora-4-unidades-de-cepillo\/"},"modified":"2026-06-03T13:27:28","modified_gmt":"2026-06-03T13:27:28","slug":"cepilladora-4-unidades-de-cepillo","status":"publish","type":"producten","link":"https:\/\/trivec.eu\/es\/producten\/cepilladora-4-unidades-de-cepillo\/","title":{"rendered":"Cepilladora &#8211; 4 unidades de cepillo"},"content":{"rendered":"<p>La Cepilladora Trivec con 4 unidades de cepillos es una m\u00e1quina industrial vers\u00e1til dise\u00f1ada para estructurar, cepillar y pulir superficies de madera para conseguir efectos est\u00e9ticos y t\u00e1ctiles espec\u00edficos.<\/p>\n<p>Esta m\u00e1quina es ideal para talleres de carpinter\u00eda, fabricantes de muebles y productores de suelos que necesitan procesar eficazmente piezas de madera para crear acabados texturizados, preparar superficies para tratamientos posteriores o conseguir aspectos envejecidos. Resuelve el problema de conseguir efectos de cepillado uniformes y precisos en diversos materiales y aplicaciones de madera. <\/p>\n","protected":false},"featured_media":17435,"parent":0,"template":"","branches":[157,158,159,160],"types":[185,186],"technieken":[183],"class_list":["post-17417","producten","type-producten","status-publish","has-post-thumbnail","hentry","branches-parquet","branches-madera-exterior","branches-madera-interior","branches-otros","types-cepillado","types-lijado","technieken-soluciones-de-superficie"],"_links":{"self":[{"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/producten\/17417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/producten"}],"about":[{"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/types\/producten"}],"version-history":[{"count":2,"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/producten\/17417\/revisions"}],"predecessor-version":[{"id":18559,"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/producten\/17417\/revisions\/18559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/media\/17435"}],"wp:attachment":[{"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/media?parent=17417"}],"wp:term":[{"taxonomy":"branches","embeddable":true,"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/branches?post=17417"},{"taxonomy":"types","embeddable":true,"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/types?post=17417"},{"taxonomy":"technieken","embeddable":true,"href":"https:\/\/trivec.eu\/es\/wp-json\/wp\/v2\/technieken?post=17417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}