{"id":17056,"date":"2024-12-05T17:04:38","date_gmt":"2024-12-05T17:04:38","guid":{"rendered":"https:\/\/trivec.eu\/producten\/coupe-coupe-premium\/"},"modified":"2024-12-05T17:04:38","modified_gmt":"2024-12-05T17:04:38","slug":"coupe-coupe-premium","status":"publish","type":"producten","link":"https:\/\/trivec.eu\/fr\/producten\/coupe-coupe-premium\/","title":{"rendered":"Coupe-coupe Premium"},"content":{"rendered":"<p>Con\u00e7ue pour cr\u00e9er des effets de scie \u00e0 ruban sur des surfaces en bois, elle comprend une scie \u00e0 ruban et trois unit\u00e9s de brossage. La version Premium comprend une cabine avec des fen\u00eatres, des portes coulissantes et un interrupteur de s\u00e9curit\u00e9, garantissant un environnement plus s\u00fbr et sans poussi\u00e8re. <\/p>\n<p>Gr\u00e2ce au r\u00e9glage de la vitesse de passage, de la vitesse de coupe transversale, des angles de l&rsquo;unit\u00e9, des types de brosses et des bandes de coupe transversale, il peut produire des effets vari\u00e9s. Le syst\u00e8me Trivec Tapper en option ajoute des effets uniques et naturels en utilisant des sabots pneumatiques pour une pression al\u00e9atoire de la courroie. \u00c9quip\u00e9 d&rsquo;un \u00e9cran tactile, il permet de r\u00e9gler et de m\u00e9moriser facilement les param\u00e8tres de vitesse, de hauteur d&rsquo;unit\u00e9 et de programmes. Les brosses et les courroies peuvent \u00eatre rapidement remplac\u00e9es.   <\/p>\n","protected":false},"featured_media":17058,"parent":0,"template":"","branches":[166,167,168],"types":[187,180,181],"technieken":[179],"class_list":["post-17056","producten","type-producten","status-publish","has-post-thumbnail","hentry","branches-parquet","branches-bois-exterieur","branches-bois-interieur","types-coupe-coupe","types-brossage","types-sablage","technieken-solutions-de-surface"],"_links":{"self":[{"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/producten\/17056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/producten"}],"about":[{"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/types\/producten"}],"version-history":[{"count":0,"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/producten\/17056\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/media\/17058"}],"wp:attachment":[{"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/media?parent=17056"}],"wp:term":[{"taxonomy":"branches","embeddable":true,"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/branches?post=17056"},{"taxonomy":"types","embeddable":true,"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/types?post=17056"},{"taxonomy":"technieken","embeddable":true,"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/technieken?post=17056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}