{"id":17349,"date":"2024-12-05T17:04:44","date_gmt":"2024-12-05T17:04:44","guid":{"rendered":"https:\/\/trivec.eu\/producten\/convoyeurs-de-transport\/"},"modified":"2024-12-05T17:04:44","modified_gmt":"2024-12-05T17:04:44","slug":"convoyeurs-de-transport","status":"publish","type":"producten","link":"https:\/\/trivec.eu\/fr\/producten\/convoyeurs-de-transport\/","title":{"rendered":"Convoyeurs de transport"},"content":{"rendered":"<p>Les convoyeurs de transport Trivec sont con\u00e7us pour le d\u00e9placement efficace des pi\u00e8ces entre les machines d&rsquo;une cha\u00eene de production. Disponibles en version standard ou sur mesure, ils supportent des largeurs de travail allant de 150 mm \u00e0 1450 mm et sont propos\u00e9s en diff\u00e9rentes longueurs pour r\u00e9pondre aux exigences sp\u00e9cifiques de la production. <\/p>\n<p>Gr\u00e2ce \u00e0 sa conception modulaire et \u00e0 sa construction robuste, le syst\u00e8me garantit des performances fiables et une int\u00e9gration ais\u00e9e dans les processus de production.<\/p>\n","protected":false},"featured_media":17358,"parent":0,"template":"","branches":[163,166,167,168],"types":[197],"technieken":[196],"class_list":["post-17349","producten","type-producten","status-publish","has-post-thumbnail","hentry","branches-autre","branches-parquet","branches-bois-exterieur","branches-bois-interieur","types-convoyeurs","technieken-solutions-de-manutention"],"_links":{"self":[{"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/producten\/17349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/producten"}],"about":[{"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/types\/producten"}],"version-history":[{"count":0,"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/producten\/17349\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/media\/17358"}],"wp:attachment":[{"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/media?parent=17349"}],"wp:term":[{"taxonomy":"branches","embeddable":true,"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/branches?post=17349"},{"taxonomy":"types","embeddable":true,"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/types?post=17349"},{"taxonomy":"technieken","embeddable":true,"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/technieken?post=17349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}