{"id":17879,"date":"2024-12-05T17:04:57","date_gmt":"2024-12-05T17:04:57","guid":{"rendered":"https:\/\/trivec.eu\/producten\/machine-a-pulveriser-tmq\/"},"modified":"2026-06-03T13:32:34","modified_gmt":"2026-06-03T13:32:34","slug":"machine-a-pulveriser-tmq","status":"publish","type":"producten","link":"https:\/\/trivec.eu\/fr\/producten\/machine-a-pulveriser-tmq\/","title":{"rendered":"Machine \u00e0 pulv\u00e9riser TMQ"},"content":{"rendered":"<p>La machine \u00e0 pulv\u00e9riser TMQ recouvre efficacement de peintures, de laques et de teintures les pi\u00e8ces longues et fines telles que les plinthes, les parquets et les profil\u00e9s, garantissant ainsi une qualit\u00e9 constante et un minimum de d\u00e9chets.<\/p>\n<p>Son convoyeur r\u00e9sistant aux laques garantit une application uniforme, tandis que le syst\u00e8me int\u00e9gr\u00e9 d&rsquo;overspray collecte, filtre et recycle l&rsquo;exc\u00e8s de mat\u00e9riau. Le TMQ s&rsquo;adapte \u00e0 diff\u00e9rentes tailles de pi\u00e8ces, prend en charge les rev\u00eatements \u00e0 base d&rsquo;eau et de solvant, et dispose d&rsquo;un syst\u00e8me d&rsquo;aspiration double face pour maintenir un espace de travail propre. Des modules d&rsquo;alimentation et de sortie optionnels permettent une int\u00e9gration transparente dans les lignes de production automatis\u00e9es pour une meilleure \u00e9volutivit\u00e9 et une plus grande flexibilit\u00e9.  <\/p>\n","protected":false},"featured_media":17888,"parent":0,"template":"","branches":[163,166,167,168],"types":[175],"technieken":[164],"class_list":["post-17879","producten","type-producten","status-publish","has-post-thumbnail","hentry","branches-autre","branches-parquet","branches-bois-exterieur","branches-bois-interieur","types-pulverisateurs","technieken-solutions-de-revetement"],"_links":{"self":[{"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/producten\/17879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/producten"}],"about":[{"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/types\/producten"}],"version-history":[{"count":1,"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/producten\/17879\/revisions"}],"predecessor-version":[{"id":19488,"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/producten\/17879\/revisions\/19488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/media\/17888"}],"wp:attachment":[{"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/media?parent=17879"}],"wp:term":[{"taxonomy":"branches","embeddable":true,"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/branches?post=17879"},{"taxonomy":"types","embeddable":true,"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/types?post=17879"},{"taxonomy":"technieken","embeddable":true,"href":"https:\/\/trivec.eu\/fr\/wp-json\/wp\/v2\/technieken?post=17879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}